{"id":1563,"date":"2025-12-04T16:48:03","date_gmt":"2025-12-04T16:48:03","guid":{"rendered":"https:\/\/www.foroconvivenciacordoba.org\/pas-de-convivance-sans-bonne-communication-le-160e-anniversaire-de-la-creation-de-lunion-internationale-du-telegraphe-uti\/"},"modified":"2026-05-06T18:00:34","modified_gmt":"2026-05-06T18:00:34","slug":"pas-de-convivance-sans-bonne-communication-le-160e-anniversaire-de-la-creation-de-lunion-internationale-du-telegraphe-uti","status":"publish","type":"post","link":"https:\/\/www.foroconvivenciacordoba.org\/fr\/pas-de-convivance-sans-bonne-communication-le-160e-anniversaire-de-la-creation-de-lunion-internationale-du-telegraphe-uti\/","title":{"rendered":"Il n\u2019y a pas de convivance sans bonne communication"},"content":{"rendered":"\n<h5 class=\"wp-block-heading\"><strong>Le 160e anniversaire de la cr\u00e9ation de l\u2019Union t\u00e9l\u00e9graphique internationale (UTI)<\/strong><\/h5>\n\n<p>L\u2019histoire de l\u2019UIT est celle de la connexion humaine, partie int\u00e9grante d\u2019une Convivance indispensable. Elle a commenc\u00e9 par relier peuples et continents gr\u00e2ce aux c\u00e2bles t\u00e9l\u00e9graphiques et g\u00e8re aujourd\u2019hui le flux de donn\u00e9es num\u00e9riques, base de notre \u00e9conomie et de notre soci\u00e9t\u00e9 \u00e0 l\u2019\u00e9chelle mondiale. C\u00e9l\u00e9brer ses 160 ans, c\u2019est reconna\u00eetre que, derri\u00e8re chaque appel, chaque message texte et chaque vid\u00e9o en ligne, se trouvent plus d\u2019un si\u00e8cle et demi de travail collaboratif, de normalisation et une vision partag\u00e9e : la communication comme droit fondamental et force de progr\u00e8s global pour la Convivance.  <\/p>\n\n<p>C\u00e9l\u00e9brer le 160e anniversaire de la cr\u00e9ation de l\u2019Union t\u00e9l\u00e9graphique internationale (UTI), pr\u00e9curseur de l\u2019Union internationale des t\u00e9l\u00e9communications (UIT), c\u2019est rappeler l\u2019un des piliers fondamentaux de la communication mondiale. Au milieu du XIXe si\u00e8cle, le t\u00e9l\u00e9graphe \u00e9lectrique \u00e9tait une r\u00e9volution. Pour la premi\u00e8re fois, les messages pouvaient voyager plus vite qu\u2019un train ou un navire. Cependant, un probl\u00e8me majeur subsistait : le manque de normalisation. Face \u00e0 cette n\u00e9cessit\u00e9, la France a pris l\u2019initiative et a convoqu\u00e9 20 pays \u00e0 une conf\u00e9rence \u00e0 Paris.    <\/p>\n\n<p>Vingt \u00e9tats fondateurs ont sign\u00e9 la Convention t\u00e9l\u00e9graphique internationale et cr\u00e9\u00e9 l\u2019Union t\u00e9l\u00e9graphique internationale (UTI) \u00e0 Paris le 17 mai 1865. Ces vingt pays se sont r\u00e9unis sous la pr\u00e9sidence d\u2019\u00c9douard Drouyn de Lhuys et ont sign\u00e9 la premi\u00e8re convention t\u00e9l\u00e9graphique internationale, cr\u00e9ant l\u2019organisation que nous connaissons aujourd\u2019hui sous le nom d\u2019UIT. L\u2019Angleterre n\u2019a pas \u00e9t\u00e9 invit\u00e9e \u00e0 la conf\u00e9rence, car ses services t\u00e9l\u00e9graphiques \u00e9taient entre les mains de compagnies priv\u00e9es.  <\/p>\n\n<p>Ce jour-l\u00e0, les repr\u00e9sentants ont sign\u00e9 la premi\u00e8re \u00ab Convention t\u00e9l\u00e9graphique internationale \u00bb et cr\u00e9\u00e9 l\u2019Union t\u00e9l\u00e9graphique internationale avec pour objectif d\u2019\u00e9tablir des normes techniques communes afin de garantir l\u2019interop\u00e9rabilit\u00e9 des r\u00e9seaux t\u00e9l\u00e9graphiques internationaux. Il a \u00e9t\u00e9 convenu de cr\u00e9er un R\u00e8glement t\u00e9l\u00e9graphique, qui normalisait des aspects tels que les tarifs, les priorit\u00e9s des messages et, surtout, les codes de conduite des op\u00e9rateurs. <\/p>\n\n<p>Ce fut un jalon historique ; l\u2019UTI est devenue la premi\u00e8re organisation internationale permanente d\u00e9di\u00e9e aux questions techniques, \u00e9tablissant un pr\u00e9c\u00e9dent pour la coop\u00e9ration mondiale et une meilleure compr\u00e9hension entre les peuples.<\/p>\n\n<p>Avec l\u2019invention de la radio, de la t\u00e9l\u00e9graphie sans fil (TSF) de Marconi et d\u2019autres, un nouveau moyen de communication est apparu, d\u00e9passant les fronti\u00e8res. L\u2019UTI a d\u00fb s\u2019adapter. Elle ne s\u2019est pas repos\u00e9e sur ses lauriers. Son \u00e9volution a \u00e9t\u00e9 parall\u00e8le \u00e0 celle de la technologie :   <\/p>\n\n<p>T\u00e9l\u00e9phonie et radio : elle a g\u00e9r\u00e9 le spectre radio\u00e9lectrique au niveau mondial, en attribuant des fr\u00e9quences afin d\u2019\u00e9viter les interf\u00e9rences entre pays (de l\u2019aviation civile aux stations de radio et aux satellites de communication).<\/p>\n\n<p>T\u00e9l\u00e9vision et communications par satellite : elle a \u00e9tabli les normes pour la t\u00e9l\u00e9vision en couleur (comme le PAL, le SECAM et le NTSC, bien qu\u2019aujourd\u2019hui des normes num\u00e9riques soient utilis\u00e9es) et a coordonn\u00e9 les orbites des satellites de communication.<\/p>\n\n<p>\u00c8re num\u00e9rique et Internet : son r\u00f4le est devenu plus crucial que jamais :<\/p>\n\n<p>Normes techniques (UIT-T) : elle \u00e9labore les normes qui rendent possible la communication de donn\u00e9es, telles que X.25, ainsi que la compression vid\u00e9o (H.264 et H.265) et les protocoles \u00e0 large bande.<\/p>\n\n<p>Spectre et orbites (UIT-R) : elle coordonne l\u2019utilisation du spectre pour des technologies telles que la 5G, le Wi-Fi, le GPS, ainsi que les orbites g\u00e9ostationnaires des satellites de communication.<\/p>\n\n<p>D\u00e9veloppement (UIT-D) : elle \u0153uvre pour r\u00e9duire la \u00ab fracture num\u00e9rique \u00bb, en apportant l\u2019acc\u00e8s \u00e0 Internet et aux t\u00e9l\u00e9communications aux pays en d\u00e9veloppement.<\/p>\n\n<p>\u00c0 160 ans, l\u2019UIT est une organisation indispensable. Ses d\u00e9fis actuels et futurs incluent : <\/p>\n\n<ul class=\"wp-block-list\">\n<li>Garantir la cybers\u00e9curit\u00e9 des r\u00e9seaux publics.<\/li>\n\n\n\n<li>Gouverner l\u2019intelligence artificielle (IA) dans les t\u00e9l\u00e9communications.<\/li>\n\n\n\n<li>Connecter les populations non connect\u00e9es (des milliards de personnes n\u2019ont toujours pas acc\u00e8s \u00e0 Internet).<\/li>\n\n\n\n<li>G\u00e9rer la transition vers la 6G.<\/li>\n\n\n\n<li>Promouvoir la neutralit\u00e9 du Net et les droits num\u00e9riques dans un monde hyperconnect\u00e9.<\/li>\n<\/ul>\n\n<p>Les groupes d\u2019ing\u00e9nieurs et les \u00e9quipes de travail, ponctuels et permanents, proposent des recommandations de normes qui, une fois approuv\u00e9es, deviennent des standards \u00e0 suivre par les fabricants d\u2019\u00e9quipements de t\u00e9l\u00e9communications \u00e0 l\u2019\u00e9chelle mondiale.<\/p>\n\n<p><strong><strong>Madrid 1932 : l\u00e0 o\u00f9 la t\u00e9l\u00e9graphie est devenue t\u00e9l\u00e9communication <\/strong> <\/strong><\/p>\n\n<p>Dans l\u2019histoire des communications mondiales, tandis que Paris d\u00e9tient le titre de berceau de l\u2019Union t\u00e9l\u00e9graphique internationale en 1865, Madrid occupe une place tout aussi cruciale : celle de son nouveau nom. C\u2019est dans la capitale espagnole qu\u2019en 1932, l\u2019organisation a \u00e9volu\u00e9 pour adopter le nom qui est aujourd\u2019hui un pilier du monde num\u00e9rique : l\u2019Union internationale des t\u00e9l\u00e9communications (UIT), avec les repr\u00e9sentants de plus de 80 pays.  <\/p>\n\n<p>L\u2019objectif \u00e9tait ambitieux : unifier dans un seul cadre juridique l\u2019ensemble des communications \u00e0 distance. Le r\u00e9sultat fut la signature de la Convention de Madrid. L\u2019acte le plus symbolique de cette conf\u00e9rence fut la d\u00e9cision de fusionner l\u2019UTI et l\u2019Union radiot\u00e9l\u00e9graphique internationale (URI) en une seule organisation. Pour refl\u00e9ter cette nouvelle r\u00e9alit\u00e9 int\u00e9gratrice, qui s\u2019\u00e9tendait du t\u00e9l\u00e9graphe \u00e0 la radio, un nouveau nom fut choisi : Union internationale des t\u00e9l\u00e9communications (UIT). C\u2019est ainsi qu\u2019est n\u00e9e une institution pr\u00eate pour l\u2019avenir.    <\/p>\n\n<p>L\u2019\u00e9v\u00e9nement de Madrid ne fut pas un simple changement de nom ; il constitua une red\u00e9finition de la mission de l\u2019organisation. Il marqua la transition d\u2019une \u00e8re centr\u00e9e sur une seule technologie (le t\u00e9l\u00e9graphe) vers une vision globale des \u00ab t\u00e9l\u00e9communications \u00bb, un terme englobant toutes les formes de communication \u00e0 distance. C\u2019est pourquoi Madrid constitue un chapitre essentiel de l\u2019histoire de l\u2019entit\u00e9 qui, aujourd\u2019hui, r\u00e9git le spectre radio\u00e9lectrique et pose les bases techniques de notre \u00e8re num\u00e9rique.  <\/p>\n\n<p><strong>Nicol\u00e1s Puerto Barrios<\/strong><br\/>Ing\u00e9nieur technique en t\u00e9l\u00e9communications. Cordoue <\/p>\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019histoire de l\u2019UIT est celle de la connexion humaine. Du t\u00e9l\u00e9graphe \u00e0 l\u2019\u00e8re num\u00e9rique, elle a favoris\u00e9 la coop\u00e9ration internationale, la normalisation technique et l\u2019acc\u00e8s mondial aux t\u00e9l\u00e9communications. Aujourd\u2019hui, elle reste essentielle pour la connectivit\u00e9, l\u2019innovation et la convivance dans un monde toujours plus interd\u00e9pendant.  <\/p>\n","protected":false},"author":1,"featured_media":1562,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kadence_starter_templates_imported_post":false,"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"categories":[33],"tags":[],"class_list":["post-1563","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-chroniques"],"taxonomy_info":{"category":[{"value":33,"label":"chroniques"}]},"featured_image_src_large":["https:\/\/www.foroconvivenciacordoba.org\/wp-content\/uploads\/2025\/12\/uit_fundacion.jpg",1024,644,false],"author_info":{"display_name":"administrador","author_link":"https:\/\/www.foroconvivenciacordoba.org\/fr\/author\/administrador\/"},"comment_info":0,"category_info":[{"term_id":33,"name":"chroniques","slug":"chroniques","term_group":0,"term_taxonomy_id":33,"taxonomy":"category","description":"","parent":0,"count":10,"filter":"raw","cat_ID":33,"category_count":10,"category_description":"","cat_name":"chroniques","category_nicename":"chroniques","category_parent":0}],"tag_info":false,"_links":{"self":[{"href":"https:\/\/www.foroconvivenciacordoba.org\/fr\/wp-json\/wp\/v2\/posts\/1563","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.foroconvivenciacordoba.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.foroconvivenciacordoba.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.foroconvivenciacordoba.org\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.foroconvivenciacordoba.org\/fr\/wp-json\/wp\/v2\/comments?post=1563"}],"version-history":[{"count":8,"href":"https:\/\/www.foroconvivenciacordoba.org\/fr\/wp-json\/wp\/v2\/posts\/1563\/revisions"}],"predecessor-version":[{"id":3107,"href":"https:\/\/www.foroconvivenciacordoba.org\/fr\/wp-json\/wp\/v2\/posts\/1563\/revisions\/3107"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.foroconvivenciacordoba.org\/fr\/wp-json\/wp\/v2\/media\/1562"}],"wp:attachment":[{"href":"https:\/\/www.foroconvivenciacordoba.org\/fr\/wp-json\/wp\/v2\/media?parent=1563"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.foroconvivenciacordoba.org\/fr\/wp-json\/wp\/v2\/categories?post=1563"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.foroconvivenciacordoba.org\/fr\/wp-json\/wp\/v2\/tags?post=1563"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}